{"id":29302,"date":"2026-05-12T13:59:18","date_gmt":"2026-05-12T16:59:18","guid":{"rendered":"https:\/\/novosaopaulo.com.br\/n1\/?p=29302"},"modified":"2026-05-12T13:59:19","modified_gmt":"2026-05-12T16:59:19","slug":"festa-do-divino-de-mogi-abertura-da-413a-edicao-acontece-nesta-quinta-14-com-a-troca-e-apresentacao-das-bandeiras-na-residencia-dos-festeiros-e-programacao-religiosa-e-social","status":"publish","type":"post","link":"https:\/\/novosaopaulo.com.br\/n1\/festa-do-divino-de-mogi-abertura-da-413a-edicao-acontece-nesta-quinta-14-com-a-troca-e-apresentacao-das-bandeiras-na-residencia-dos-festeiros-e-programacao-religiosa-e-social\/","title":{"rendered":"Festa do Divino de Mogi: abertura da 413\u00aa edi\u00e7\u00e3o acontece nesta quinta (14) com a troca e apresenta\u00e7\u00e3o das bandeiras na resid\u00eancia dos festeiros e programa\u00e7\u00e3o religiosa e social"},"content":{"rendered":"\n<p>Durante 11 dias, a Festa do Divino Esp\u00edrito Santo de Mogi das Cruzes transforma a Cidade em um grande cen\u00e1rio de f\u00e9, tradi\u00e7\u00e3o e solidariedade. Entre os dias 14 de maio e 24 de maio, o Munic\u00edpio literalmente respira a festa, que re\u00fane dezenas de devotos, volunt\u00e1rios e visitantes em uma das manifesta\u00e7\u00f5es culturais e religiosas mais importantes do Alto Tiet\u00ea, do Estado de S\u00e3o Paulo e do Brasil.<\/p>\n\n\n\n<p>A 413\u00aa edi\u00e7\u00e3o chega com o tema \u201cDivino Esp\u00edrito Santo, fazei de n\u00f3s mensageiros da vossa Paz\u201d, conduzida pelos Festeiros Ricardo Medina Alvarez e Maria de Lourdes Pereira da Silva Medina, ao lado dos Capit\u00e3es de Mastro Maur\u00edcio de Lima Ramos e Tavane Prado Rodrigues Ramos. Desde que assumiram a miss\u00e3o, em 2025, nomeados pelo bispo da Diocese de Mogi, dom Pedro Luiz Stringhini, os organizadores t\u00eam preparado cada detalhe com dedica\u00e7\u00e3o, para manter viva uma tradi\u00e7\u00e3o centen\u00e1ria que mobiliza cerca de quatro mil volunt\u00e1rios \u2013 dos quais dois mil est\u00e3o concentrados apenas na Quermesse &#8211; e deve atrair aproximadamente 400 mil pessoas ao longo dos dias de celebra\u00e7\u00e3o.<\/p>\n\n\n\n<p>A abertura oficial, nesta quinta-feira (14), marca o in\u00edcio dessa imers\u00e3o religiosa e cultural. A programa\u00e7\u00e3o come\u00e7a \u00e0s 15h, com a cerim\u00f4nia de troca e apresenta\u00e7\u00e3o das novas bandeiras na casa dos Festeiros, na Vila Su\u00edssa, onde, tradicionalmente, um grupo de devotos j\u00e1 se re\u00fane para conferir o layout das novas Bandeiras. Neste ato, a Congada Batalh\u00e3o Nossa Senhora Aparecida se faz presente, louvando o Esp\u00edrito Santo, em altar montado na resid\u00eancia. Logo em seguida, todos seguem em cortejo at\u00e9 a Prefeitura de Mogi das Cruzes. \u00c0s 16h30, autoridades municipais, dentre eles a prefeita de Mogi, Mara Bertaiolli, seu vice, T\u00e9o Cusatis, e o bispo da Diocese de Mogi, Dom Pedro Luiz Stringhini, recebem os participantes, e, na sequ\u00eancia, \u00e0s 17h, um novo cortejo segue at\u00e9 a Pra\u00e7a Coronel Benedito de Almeida, onde est\u00e1 instalado o Imp\u00e9rio.<\/p>\n\n\n\n<p>\u00c0s 18h, ocorre a cerim\u00f4nia oficial de abertura, com a b\u00ean\u00e7\u00e3o das bandeiras, do mastro e do Imp\u00e9rio, conduzida pelo bispo diocesano. O momento re\u00fane Festeiros e ex-Festeiros, Capit\u00e3es de Mastro e ex-Capit\u00e3es de Mastro, autoridades, devotos e a Congada, que segue em cortejo pelas ruas da Cidade at\u00e9 o Mogilar, levando simbolicamente o esp\u00edrito da festa para al\u00e9m do centro hist\u00f3rico.<\/p>\n\n\n\n<p>A partir da noite de abertura, o clima festivo ganha ainda mais for\u00e7a com a Quermesse, que ser\u00e1 realizada no Centro Municipal Integrado (CMI) \u201cDeputado Maur\u00edcio Najar\u201d, com acesso pela Avenida C\u00edvica, no Mogilar. O espa\u00e7o j\u00e1 come\u00e7a a receber o p\u00fablico a partir das 18h, com abertura oficial \u00e0s 20h. A programa\u00e7\u00e3o, para o dia da abertura, inclui atra\u00e7\u00f5es como o Cantinho da Viola, com apresenta\u00e7\u00f5es musicais a partir das 19h30, e o show da cantora Mariangela Zan, apresentadora da TV Aparecida, \u00e0s 20h30, no palco principal.<\/p>\n\n\n\n<p>Um dos grandes destaques da festa \u00e9 a gastronomia, considerada uma verdadeira experi\u00eancia cultural. S\u00e3o mais de 130 pratos t\u00edpicos, preparados por cerca de 28 entidades assistenciais em mais de 30 barracas. A quermesse recebe diariamente entre 15 e 20 mil visitantes e deve concentrar mais de 250 mil pessoas durante todo o evento. Al\u00e9m de celebrar a cultura popular, toda a renda arrecadada \u00e9 destinada a projetos sociais dessas entidades, o que refor\u00e7a o car\u00e1ter solid\u00e1rio da festividade. H\u00e1, ainda, as missas da Novena, de 15 de maio a 23 de maio, a partir das 19 horas, na Catedral de Sant\u00b4Ana; as Alvoradas, de 16 de maio a 25 de maio, com sa\u00edda \u00e0s 5 horas, do Imp\u00e9rio, em frente \u00e0 Catedral de Sant\u00b4Ana, no Centro da Cidade; a Caminhada Ecol\u00f3gica; as duas Missas Campais, no espa\u00e7o da Quermesse, nos s\u00e1bados (16 e 23), \u00e0s 15 horas; a Entrada dos Palmitos, no dia 23 de maio, \u00e0s 9 horas; a Prociss\u00e3o de Pentecostes, dentre tantas outras atividades religiosas e culturais.<\/p>\n\n\n\n<p>A programa\u00e7\u00e3o completa pode ser conferida no site da Festa do Divino (https:\/\/festadodivino.org.br\/) ou nas redes sociais: Facebook (https:\/\/www.facebook.com\/festadodivinodemogidascruzes?locale=pt_BR) e Instagram (https:\/\/www.instagram.com\/divinomogi\/).<\/p>\n\n\n\n<p>A Quermesse est\u00e1 localizada no Centro Municipal Integrado (CMI) \u201cDeputado Deputado Maur\u00edcio Najar\u201d, com acesso pela Avenida C\u00edvica, s\/n\u00ba, no Mogilar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante 11 dias, a Festa do Divino Esp\u00edrito Santo de Mogi das Cruzes transforma a&#8230;<\/p>\n","protected":false},"author":1,"featured_media":29303,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"featured_image_urls":{"full":["https:\/\/novosaopaulo.com.br\/n1\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-13.57.51.jpeg",1600,1066,false],"thumbnail":["https:\/\/novosaopaulo.com.br\/n1\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-13.57.51-150x150.jpeg",150,150,true],"medium":["https:\/\/novosaopaulo.com.br\/n1\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-13.57.51-300x200.jpeg",300,200,true],"medium_large":["https:\/\/novosaopaulo.com.br\/n1\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-13.57.51-768x512.jpeg",640,427,true],"large":["https:\/\/novosaopaulo.com.br\/n1\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-13.57.51-1024x682.jpeg",640,426,true],"1536x1536":["https:\/\/novosaopaulo.com.br\/n1\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-13.57.51-1536x1023.jpeg",1536,1023,true],"2048x2048":["https:\/\/novosaopaulo.com.br\/n1\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-13.57.51.jpeg",1600,1066,false],"newsever-slider-full":["https:\/\/novosaopaulo.com.br\/n1\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-13.57.51-1280x845.jpeg",1280,845,true],"newsever-featured":["https:\/\/novosaopaulo.com.br\/n1\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-13.57.51-1024x682.jpeg",1024,682,true],"newsever-medium":["https:\/\/novosaopaulo.com.br\/n1\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-13.57.51-720x475.jpeg",720,475,true]},"author_info":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/novosaopaulo.com.br\/n1\/author\/g5poa\/"},"category_info":"<a href=\"https:\/\/novosaopaulo.com.br\/n1\/category\/cidades\/\" rel=\"category tag\">Cidades<\/a>","tag_info":"Cidades","comment_count":"0","_links":{"self":[{"href":"https:\/\/novosaopaulo.com.br\/n1\/wp-json\/wp\/v2\/posts\/29302"}],"collection":[{"href":"https:\/\/novosaopaulo.com.br\/n1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novosaopaulo.com.br\/n1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novosaopaulo.com.br\/n1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novosaopaulo.com.br\/n1\/wp-json\/wp\/v2\/comments?post=29302"}],"version-history":[{"count":1,"href":"https:\/\/novosaopaulo.com.br\/n1\/wp-json\/wp\/v2\/posts\/29302\/revisions"}],"predecessor-version":[{"id":29304,"href":"https:\/\/novosaopaulo.com.br\/n1\/wp-json\/wp\/v2\/posts\/29302\/revisions\/29304"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novosaopaulo.com.br\/n1\/wp-json\/wp\/v2\/media\/29303"}],"wp:attachment":[{"href":"https:\/\/novosaopaulo.com.br\/n1\/wp-json\/wp\/v2\/media?parent=29302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novosaopaulo.com.br\/n1\/wp-json\/wp\/v2\/categories?post=29302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novosaopaulo.com.br\/n1\/wp-json\/wp\/v2\/tags?post=29302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}